{"id":1913,"date":"2019-08-12T11:19:06","date_gmt":"2019-08-12T15:19:06","guid":{"rendered":"https:\/\/engenhariacivil.ufms.br\/?p=1913"},"modified":"2019-10-24T11:10:41","modified_gmt":"2019-10-24T15:10:41","slug":"aviso-ajuste-de-matricula-2019-2","status":"publish","type":"post","link":"https:\/\/engenhariacivil-faeng.ufms.br\/en\/aviso-ajuste-de-matricula-2019-2\/","title":{"rendered":"Aviso: ajuste de matr\u00edcula 2019.2"},"content":{"rendered":"<p>AOS ALUNOS DE GRADUA\u00c7\u00c3O EM ENGENHARIA CIVIL<\/p>\n<p>As solicita\u00e7\u00f5es de ajuste de matr\u00edcula enviadas at\u00e9 o momento foram atendidas. Para os casos indeferidos, e-mails individuais j\u00e1 foram encaminhados.<\/p>\n<p>Pedimos a todos os alunos que confiram o hist\u00f3rico escolar (gerado pelo SISCAD) para saberem as disciplinas matriculadas neste semestre.<br \/>\nNesta semana (12\/08 a 16\/08\/2019) a PROGRAD bloqueou a altera\u00e7\u00e3o de quantidade de vagas e lista de oferta de disciplinas. <em>Portanto, n\u00e3o conseguiremos mais atender as demandas de matr\u00edculas e altera\u00e7\u00f5es de turma<\/em>. Entretanto, exclus\u00f5es de turma ainda podem ser realizadas.<\/p>\n<p>Para casos especiais de ajuste de matr\u00edcula, o aluno deve fazer um <a href=\"https:\/\/prograd.ufms.br\/requerimento-academico\/\" target=\"_blank\" rel=\"noopener noreferrer\">Requerimento Acad\u00eamico<\/a> pelo site da PROGRAD. O requerimento deve ser suficientemente detalhado para que seja analisado pelo curso e, se aprovado, encaminhado devidamente.<\/p>\n<p>&nbsp;<\/p>\n<p>Atenciosamente,<br \/>\nProf. Arthur Santos Silva (coordenador em exerc\u00edcio)<br \/>\nCurso de Gradua\u00e7\u00e3o em Engenharia Civil da FAENG\/UFMS<br \/>\nCampo Grande, MS, 12 de agosto de 2019<\/p>\n","protected":false},"excerpt":{"rendered":"<p>AOS ALUNOS DE GRADUA\u00c7\u00c3O EM ENGENHARIA CIVIL As solicita\u00e7\u00f5es de ajuste de matr\u00edcula enviadas at\u00e9 o momento foram atendidas. Para os casos indeferidos, e-mails individuais j\u00e1 foram encaminhados. Pedimos a todos os alunos que confiram o hist\u00f3rico escolar (gerado pelo SISCAD) para saberem as disciplinas matriculadas neste semestre. Nesta semana (12\/08 a 16\/08\/2019) a PROGRAD [&hellip;]<\/p>\n","protected":false},"author":18957,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,1],"tags":[],"coauthors":[],"class_list":["post-1913","post","type-post","status-publish","format-standard","hentry","category-destaques","category-noticias"],"_links":{"self":[{"href":"https:\/\/engenhariacivil-faeng.ufms.br\/en\/wp-json\/wp\/v2\/posts\/1913","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/engenhariacivil-faeng.ufms.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/engenhariacivil-faeng.ufms.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/engenhariacivil-faeng.ufms.br\/en\/wp-json\/wp\/v2\/users\/18957"}],"replies":[{"embeddable":true,"href":"https:\/\/engenhariacivil-faeng.ufms.br\/en\/wp-json\/wp\/v2\/comments?post=1913"}],"version-history":[{"count":1,"href":"https:\/\/engenhariacivil-faeng.ufms.br\/en\/wp-json\/wp\/v2\/posts\/1913\/revisions"}],"predecessor-version":[{"id":1914,"href":"https:\/\/engenhariacivil-faeng.ufms.br\/en\/wp-json\/wp\/v2\/posts\/1913\/revisions\/1914"}],"wp:attachment":[{"href":"https:\/\/engenhariacivil-faeng.ufms.br\/en\/wp-json\/wp\/v2\/media?parent=1913"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/engenhariacivil-faeng.ufms.br\/en\/wp-json\/wp\/v2\/categories?post=1913"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/engenhariacivil-faeng.ufms.br\/en\/wp-json\/wp\/v2\/tags?post=1913"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/engenhariacivil-faeng.ufms.br\/en\/wp-json\/wp\/v2\/coauthors?post=1913"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}