{"id":4863,"date":"2023-10-31T18:22:05","date_gmt":"2023-10-31T22:22:05","guid":{"rendered":"https:\/\/engenhariacivil-faeng.ufms.br\/?p=4863"},"modified":"2023-10-31T18:22:05","modified_gmt":"2023-10-31T22:22:05","slug":"finalizacao-do-semestre-de-2023-2","status":"publish","type":"post","link":"https:\/\/engenhariacivil-faeng.ufms.br\/en\/finalizacao-do-semestre-de-2023-2\/","title":{"rendered":"Finaliza\u00e7\u00e3o do semestre de 2023\/2"},"content":{"rendered":"<p>Aos estudantes formandos e habilitados ao ENADE 2023,<\/p>\n<h2>Atualiza\u00e7\u00f5es e acompanhamento sobre o ENADE:<\/h2>\n<ul>\n<li>Os estudantes inscritos no ENADE precisam preencher o cadastro at\u00e9 o dia <strong>18\/11\/2023<\/strong> e o question\u00e1rio do estudante at\u00e9 o dia <strong>25\/11\/2023<\/strong>. Quem n\u00e3o preencher, n\u00e3o \u00e9 considerado regular pelo Inep.<\/li>\n<li>A prova do ENADE ser\u00e1 realizada no dia <strong>26\/11\/2023<\/strong>, aqui em Campo Grande &#8211; MS. Os locais de prova ser\u00e3o divulgados pelo Inep a partir do dia <strong>06\/11\/2023<\/strong> (em breve).<\/li>\n<li>O Edital com todas as datas e informa\u00e7\u00f5es sobre o ENADE \u00e9 o <a href=\"https:\/\/engenhariacivil-faeng.ufms.br\/files\/2023\/10\/EDITAL-No-37-DE-25-DE-MAIO-DE-2023-DOU-Imprensa-Nacional.pdf\" target=\"_blank\" rel=\"noopener\">EDITAL N\u00ba 37, DE 25 DE MAIO DE 2023<\/a> do INEP.<\/li>\n<li>Site oficial do ENADE: &lt; https:\/\/www.gov.br\/inep\/pt-br\/areas-de-atuacao\/avaliacao-e-exames-educacionais\/enade &gt; .<\/li>\n<\/ul>\n<h2>Sobre a cola\u00e7\u00e3o de grau:<\/h2>\n<ul>\n<li>At\u00e9 este momento, a cola\u00e7\u00e3o de grau da Cidade Universit\u00e1ria est\u00e1 prevista para ocorrer nos dias <strong>11, 12 e 13\/12\/2023<\/strong>, conforme <a href=\"https:\/\/engenhariacivil-faeng.ufms.br\/files\/2023\/10\/PORTARIA-RTR-n-1320-de-18-08-2023.pdf\" target=\"_blank\" rel=\"noopener\">PORTARIA N\u00ba 1.320-RTR\/UFMS, DE 18 DE AGOSTO DE 2023<\/a>. A data exata da cola\u00e7\u00e3o de grau da FAENG somente \u00e9 informada poucos dias antes, por decis\u00e3o do Cerimonial da UFMS.<\/li>\n<li>A UFMS publicou uma Instru\u00e7\u00e3o Normativa que, em resumo, diz que o estudante dever\u00e1 preencher uma autodeclara\u00e7\u00e3o de regularidade, conforme a <a href=\"https:\/\/engenhariacivil-faeng.ufms.br\/files\/2023\/10\/INSTRUCAO_NORMATIVA__PROGRAD_RTR__n_57__de_18_11_2021.pdf\" target=\"_blank\" rel=\"noopener\">INSTRU\u00c7\u00c3O NORMATIVA N\u00ba 57 \u2013 PROGRAD\/UFMS, DE 18 DE NOVEMBRO DE 2021<\/a> . Essa autodeclara\u00e7\u00e3o permitir\u00e1 que o estudante possa colar grau na cerim\u00f4nia oficial, antes da publica\u00e7\u00e3o da situa\u00e7\u00e3o de regularidade do ENADE.<\/li>\n<li>O INEP tamb\u00e9m publicou o <a href=\"https:\/\/engenhariacivil-faeng.ufms.br\/files\/2023\/10\/EDITAL-No-75-DE-5-DE-OUTUBRO-DE-2023-DOU-Imprensa-Nacional.pdf\" target=\"_blank\" rel=\"noopener\">EDITAL N\u00ba 75, DE 5 DE OUTUBRO DE 2023<\/a>, que menciona que o estudante dever\u00e1 sair com o caderno de provas, no dia de aplica\u00e7\u00e3o da prova do ENADE, e entregar, de forma volunt\u00e1ria, a contracapa do caderno de prova que contempla um c\u00f3digo alfanum\u00e9rico de confirma\u00e7\u00e3o de presen\u00e7a no exame. Com essa informa\u00e7\u00e3o, o coordenador de curso pode fazer algumas verifica\u00e7\u00f5es e atestar que o estudante realmente esteve na prova e est\u00e1 com situa\u00e7\u00e3o regular, autorizando a cola\u00e7\u00e3o de grau.<\/li>\n<\/ul>\n<h3>Datas importantes:<\/h3>\n<ul>\n<li>VIII &#8211; Preenchimento do cadastro pelos estudantes concluintes habilitados &#8211; Estudante &#8211; 27 de junho a 18 de novembro de 2023<\/li>\n<li>XVI &#8211; Preenchimento do Question\u00e1rio do Estudante &#8211; Estudante &#8211; 1\u00ba de setembro a 25 de novembro de 2023<\/li>\n<li>XVIII &#8211; Divulga\u00e7\u00e3o dos locais de prova no Sistema Enade &#8211; Inep &#8211; 6 a 26 de novembro de 2023<\/li>\n<li>XIX &#8211; Aplica\u00e7\u00e3o da prova &#8211; Inep &#8211; 26 de novembro de 2023<\/li>\n<li>XX &#8211; Preenchimento do Question\u00e1rio do Coordenador de Curso &#8211; Coordenador de curso &#8211; 27 de novembro a 8 de dezembro de2023<\/li>\n<li>XXI &#8211; Divulga\u00e7\u00e3o da rela\u00e7\u00e3o de estudantes em situa\u00e7\u00e3o regular no Enade 2023 &#8211; Inep &#8211; 4 de janeiro de 2024<\/li>\n<li>XXII &#8211; Registro de Declara\u00e7\u00e3o de Responsabilidade da IES &#8211; Coordenador de curso &#8211; A partir de 4 de janeiro de 2024<\/li>\n<li>XXIII &#8211; Solicita\u00e7\u00e3o de dispensa de participa\u00e7\u00e3o na prova pelo estudante &#8211; 4 de janeiro de 2024 a 9 de fevereiro de 2024<\/li>\n<li>XXVII &#8211; Recurso das solicita\u00e7\u00f5es de dispensa do estudante, indeferidas pela IES &#8211; Coordenador de curso &#8211; 21 de fevereiro a 6 de mar\u00e7o de 2024<\/li>\n<\/ul>\n<h2>Defesa do TCC e cumprimento das CCNDs:<\/h2>\n<h4>Quem pretende participar da cola\u00e7\u00e3o de grau oficial (entre os dias 11 e 13\/12\/2023):<\/h4>\n<ul>\n<li>Tendo em vista que o per\u00edodo letivo de 2023\/2 termina no dia 02\/12\/2023, as defesas de TCC devem ocorrer at\u00e9, no m\u00e1ximo, <span style=\"text-decoration: underline\">o dia de fechamento do SISCAD (<strong>05\/12\/2023<\/strong>)<\/span> para dar tempo dos tr\u00e2mites com a PROGRAD e autoriza\u00e7\u00e3o para cola\u00e7\u00e3o de grau.<\/li>\n<li>Al\u00e9m do TCC, os estudantes devem cumprir todas as demais CCNDs conforme o SISCAD de cada um, especialmente em rela\u00e7\u00e3o \u00e0s atividades de extens\u00e3o e a carga hor\u00e1ria para integraliza\u00e7\u00e3o curricular.<\/li>\n<li><\/li>\n<\/ul>\n<h4>Quem pretende defender o TCC posteriormente:<\/h4>\n<ul>\n<li>Caso os alunos n\u00e3o consigam cumprir o prazo (por qualquer motivo), a defesa de TCC pode ocorrer a qualquer momento no semestre, a crit\u00e9rio do professor orientador.<\/li>\n<li>A cola\u00e7\u00e3o de grau, no caso de estudantes que defendam o TCC e\/ou concluam as CCNDs posteriormente, ser\u00e1 realizada no Gabinete da Dire\u00e7\u00e3o da FAENG, sob demanda.<\/li>\n<li>Os alunos que est\u00e3o no PPC antigo devem se atentar para o per\u00edodo de <em>migra\u00e7\u00e3o para a estrutura curricular do novo PPC<\/em>. Assim, recomenda-se que <span style=\"text-decoration: underline\">a defesa do TCC ocorra at\u00e9, no m\u00e1ximo, <\/span><strong><span style=\"text-decoration: underline\">dia 09\/02\/2024<\/span><\/strong>. Ap\u00f3s essa data, o SISCAD come\u00e7ar\u00e1 a ser organizado para as matr\u00edculas do per\u00edodo de 2024\/1 e n\u00e3o dar\u00e1 mais tempo de manter os estudantes no PPC antigo.<\/li>\n<\/ul>\n<p>At.te,<\/p>\n<p>Prof. Arthur Santos Silva<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aos estudantes formandos e habilitados ao ENADE 2023, Atualiza\u00e7\u00f5es e acompanhamento sobre o ENADE: Os estudantes inscritos no ENADE precisam preencher o cadastro at\u00e9 o dia 18\/11\/2023 e o question\u00e1rio do estudante at\u00e9 o dia 25\/11\/2023. Quem n\u00e3o preencher, n\u00e3o \u00e9 considerado regular pelo Inep. A prova do ENADE ser\u00e1 realizada no dia 26\/11\/2023, aqui [&hellip;]<\/p>\n","protected":false},"author":18957,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,1,7],"tags":[],"coauthors":[],"class_list":["post-4863","post","type-post","status-publish","format-standard","hentry","category-destaques","category-noticias","category-pub"],"_links":{"self":[{"href":"https:\/\/engenhariacivil-faeng.ufms.br\/en\/wp-json\/wp\/v2\/posts\/4863","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/engenhariacivil-faeng.ufms.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/engenhariacivil-faeng.ufms.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/engenhariacivil-faeng.ufms.br\/en\/wp-json\/wp\/v2\/users\/18957"}],"replies":[{"embeddable":true,"href":"https:\/\/engenhariacivil-faeng.ufms.br\/en\/wp-json\/wp\/v2\/comments?post=4863"}],"version-history":[{"count":1,"href":"https:\/\/engenhariacivil-faeng.ufms.br\/en\/wp-json\/wp\/v2\/posts\/4863\/revisions"}],"predecessor-version":[{"id":4869,"href":"https:\/\/engenhariacivil-faeng.ufms.br\/en\/wp-json\/wp\/v2\/posts\/4863\/revisions\/4869"}],"wp:attachment":[{"href":"https:\/\/engenhariacivil-faeng.ufms.br\/en\/wp-json\/wp\/v2\/media?parent=4863"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/engenhariacivil-faeng.ufms.br\/en\/wp-json\/wp\/v2\/categories?post=4863"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/engenhariacivil-faeng.ufms.br\/en\/wp-json\/wp\/v2\/tags?post=4863"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/engenhariacivil-faeng.ufms.br\/en\/wp-json\/wp\/v2\/coauthors?post=4863"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}